{"id":5946,"date":"2026-02-27T10:27:48","date_gmt":"2026-02-27T09:27:48","guid":{"rendered":"https:\/\/conspiration-editions.com\/?page_id=5946"},"modified":"2026-02-27T10:27:48","modified_gmt":"2026-02-27T09:27:48","slug":"escalader-les-nuages","status":"publish","type":"page","link":"https:\/\/conspiration-editions.com\/en\/escalader-les-nuages\/","title":{"rendered":"Escalader les nuages"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5946\" class=\"elementor elementor-5946\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-594aceeb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"594aceeb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-432c9115\" data-id=\"432c9115\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c41b437 euclid elementor-widget elementor-widget-heading\" data-id=\"c41b437\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Escalader les nuages<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3dd1e6 elementor-widget elementor-widget-text-editor\" data-id=\"5f3dd1e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Nicolas Ragu<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47c0b989 elementor-widget elementor-widget-text-editor\" data-id=\"47c0b989\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>C \/ vingt-et-un<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42973362 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"42973362\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3dbb1627 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dbb1627\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-486a0d4a\" data-id=\"486a0d4a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67edd56 bt-bleu elementor-widget elementor-widget-text-editor\" data-id=\"67edd56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><div class=\"dp-element dp-lite\"  data-slug=\"escalader-les-nuages\" data-_slug=\"escalader-les-nuages\" data-title=\"lire-un-extrait\" id=\"dp_5944\" data-option=\"dp_option_5944\"  data-lightbox=\"button\">Lire un extrait<\/div><script class=\"dp-shortcode-script\" type=\"application\/javascript\">window.dp_option_5944 = {\"source\":\"https:\\\/\\\/conspiration-editions.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Escalader-les-nuages-extrait.pdf\",\"viewerType\":\"flipbook\",\"is3D\":false,\"enableSound\":false,\"slug\":\"escalader-les-nuages\",\"id\":5944}; if(window.DEARPDF && window.DEARPDF.parseElements){window.DEARPDF.parseElements();}<\/script><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3300750d\" data-id=\"3300750d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fa5b43 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5fa5b43\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Uniquement en librairie<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a840f1c elementor-align-right elementor-widget elementor-widget-button\" data-id=\"a840f1c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/conspiration-editions.com\/en\/product\/escalader-les-nuages-ebook\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ebook (9\u20ac)<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37f5ad32 elementor-widget elementor-widget-text-editor\" data-id=\"37f5ad32\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><em>Date de parution : 9 f\u00e9vrier 2023<\/em><br \/><em>130 pages &#8211; 145&#215;230 mm<\/em><br \/><span style=\"font-size: 12px;\"><em>ISBN : 979-10-95550-44-0<\/em><\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b6beeb5\" data-id=\"3b6beeb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4596da59 elementor-widget elementor-widget-image\" data-id=\"4596da59\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Escalader les nuages\" data-lbwps-width=\"980\" data-lbwps-height=\"700\" data-lbwps-srcsmall=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"536\" src=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg 980w, https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation-300x214.jpg 300w, https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation-768x549.jpg 768w, https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation-230x164.jpg 230w, https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation-600x429.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74d5d07c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74d5d07c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cc06b28\" data-id=\"6cc06b28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77423ac elementor-widget elementor-widget-text-editor\" data-id=\"77423ac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><strong>R\u00e9sum\u00e9 :<\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-227a612e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"227a612e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29e42a40\" data-id=\"29e42a40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-680e842e elementor-widget elementor-widget-text-editor\" data-id=\"680e842e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Est-ce pour reconstituer les premiers fragments de son histoire, justement, que cette jeune fille sans histoire se met si souvent en danger de vie ? Paradoxe entre la bonne \u00e9l\u00e8ve sage, bien dans sa peau, et ces plongeons dans le vide qui la pr\u00e9cipitent, le temps d\u2019une chute, dans des puits de m\u00e9moire. Le drame n\u2019est jamais loin, mais c\u2019est bien \u00e0 la vie qu\u2019elle accroche dans ces acc\u00e9l\u00e9rations hors de toute raison. Une vie qu\u2019elle aime trop pour conna\u00eetre la peur, qu\u2019elle estime assez pour ne pas s\u2019attarder sur les douleurs du corps.<br \/>L\u2019inqui\u00e9tude est pour les autres. Avec ce roman, Nicolas Ragu reprend un th\u00e8me qui lui est cher, celui de la m\u00e9moire : souvenirs cach\u00e9s, n\u00e9cessaires r\u00e9miniscences&#8230; pour mieux les remiser en paix et s\u2019ouvrir \u00e0 de nouveaux horizons.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dc90132 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dc90132\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a62b416\" data-id=\"6a62b416\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a3c86b1 elementor-widget elementor-widget-text-editor\" data-id=\"4a3c86b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><strong>L&rsquo;auteur :<br \/><\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-306d1ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"306d1ba\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f1f67\" data-id=\"6f1f67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67a648f2 elementor-widget elementor-widget-text-editor\" data-id=\"67a648f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/portrait-Nicolas-Ragu-300x234.jpg\" alt=\"Nicolas Ragu\" class=\"alignleft wp-image-5955\" title=\"Nicolas Ragu\" width=\"225\" height=\"175\" srcset=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/portrait-Nicolas-Ragu-300x234.jpg 300w, https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/portrait-Nicolas-Ragu-230x179.jpg 230w, https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/portrait-Nicolas-Ragu.jpg 473w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>Nicolas Ragu<\/strong><\/p><p>Nicolas Ragu est n\u00e9 en 1967 \u00e0 Rouen. Com\u00e9dien, il \u00e9crit des textes qu\u2019il interpr\u00e8te seul en sc\u00e8ne ou confie \u00e0 d\u2019autres. Laur\u00e9at d\u2019une bourse SACD Beaumarchais et du Prix Claude Santelli pour <em>Chrysanth\u00e8mes<\/em> (\u00e9ditions de l\u2019Amandier), romancier, il a publi\u00e9 <em>La M\u00e9moire des Sables<\/em>, pour partager l\u2019histoire qui courait dans sa t\u00eate depuis l\u2019enfance, <em>Amn\u00e9sies Lacunaires<\/em>, pour donner vie \u00e0 un r\u00eave r\u00e9current, <em>Escalader les Nuages<\/em> parce que sa fille, \u00e0 six mois dans sa poussette, lui avait fait entrevoir cette histoire. Il s\u2019int\u00e9resse aux m\u00e9canismes inconscients, l\u2019impr\u00e9gnation et tout ce qui \u00e9chappe \u00e0 la volont\u00e9.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e3be398 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e3be398\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1de4d618\" data-id=\"1de4d618\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32c0097f elementor-widget elementor-widget-spacer\" data-id=\"32c0097f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6283830 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6283830\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6dc8d82f\" data-id=\"6dc8d82f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f121911 elementor-widget elementor-widget-spacer\" data-id=\"2f121911\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Escalader les nuages Nicolas Ragu C \/ vingt-et-un Uniquement en librairie Ebook (9\u20ac) Date de parution : 9 f\u00e9vrier 2023130 pages &#8211; 145&#215;230 mmISBN : 979-10-95550-44-0 R\u00e9sum\u00e9 : Est-ce pour reconstituer les premiers fragments de son histoire, justement, que cette jeune fille sans histoire se met si souvent en danger [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escalader les nuages - Conspiration | \u00c9ditions<\/title>\n<meta name=\"description\" content=\"De Nicolas Ragu. Ce roman nous pr\u00e9cipite, le temps d\u2019une chute, dans des puits de m\u00e9moire pour choisir quoi croire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conspiration-editions.com\/en\/escalader-les-nuages\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escalader les nuages - Conspiration | \u00c9ditions\" \/>\n<meta property=\"og:description\" content=\"De Nicolas Ragu. Ce roman nous pr\u00e9cipite, le temps d\u2019une chute, dans des puits de m\u00e9moire pour choisir quoi croire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conspiration-editions.com\/en\/escalader-les-nuages\/\" \/>\n<meta property=\"og:site_name\" content=\"Conspiration | \u00c9ditions\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/\",\"url\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/\",\"name\":\"Escalader les nuages - Conspiration | \u00c9ditions\",\"isPartOf\":{\"@id\":\"https:\/\/conspiration-editions.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\",\"datePublished\":\"2026-02-27T09:27:48+00:00\",\"dateModified\":\"2026-02-27T09:27:48+00:00\",\"description\":\"De Nicolas Ragu. Ce roman nous pr\u00e9cipite, le temps d\u2019une chute, dans des puits de m\u00e9moire pour choisir quoi croire.\",\"breadcrumb\":{\"@id\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#primaryimage\",\"url\":\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\",\"contentUrl\":\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/conspiration-editions.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escalader les nuages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conspiration-editions.com\/#website\",\"url\":\"https:\/\/conspiration-editions.com\/\",\"name\":\"Conspiration | \u00c9ditions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/conspiration-editions.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conspiration-editions.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/conspiration-editions.com\/#organization\",\"name\":\"Conspiration | \u00c9ditions\",\"url\":\"https:\/\/conspiration-editions.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/conspiration-editions.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2021\/01\/cropped-cropped-cropped-logo-editions.png\",\"contentUrl\":\"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2021\/01\/cropped-cropped-cropped-logo-editions.png\",\"width\":574,\"height\":100,\"caption\":\"Conspiration | \u00c9ditions\"},\"image\":{\"@id\":\"https:\/\/conspiration-editions.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escalader les nuages - Conspiration | \u00c9ditions","description":"De Nicolas Ragu. Ce roman nous pr\u00e9cipite, le temps d\u2019une chute, dans des puits de m\u00e9moire pour choisir quoi croire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conspiration-editions.com\/en\/escalader-les-nuages\/","og_locale":"en_US","og_type":"article","og_title":"Escalader les nuages - Conspiration | \u00c9ditions","og_description":"De Nicolas Ragu. Ce roman nous pr\u00e9cipite, le temps d\u2019une chute, dans des puits de m\u00e9moire pour choisir quoi croire.","og_url":"https:\/\/conspiration-editions.com\/en\/escalader-les-nuages\/","og_site_name":"Conspiration | \u00c9ditions","og_image":[{"url":"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/","url":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/","name":"Escalader les nuages - Conspiration | \u00c9ditions","isPartOf":{"@id":"https:\/\/conspiration-editions.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#primaryimage"},"image":{"@id":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#primaryimage"},"thumbnailUrl":"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg","datePublished":"2026-02-27T09:27:48+00:00","dateModified":"2026-02-27T09:27:48+00:00","description":"De Nicolas Ragu. Ce roman nous pr\u00e9cipite, le temps d\u2019une chute, dans des puits de m\u00e9moire pour choisir quoi croire.","breadcrumb":{"@id":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conspiration-editions.com\/escalader-les-nuages\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#primaryimage","url":"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg","contentUrl":"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2023\/01\/Escalader-les-nuages-couverture-simulation.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/conspiration-editions.com\/escalader-les-nuages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/conspiration-editions.com\/"},{"@type":"ListItem","position":2,"name":"Escalader les nuages"}]},{"@type":"WebSite","@id":"https:\/\/conspiration-editions.com\/#website","url":"https:\/\/conspiration-editions.com\/","name":"Conspiration | \u00c9ditions","description":"","publisher":{"@id":"https:\/\/conspiration-editions.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conspiration-editions.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/conspiration-editions.com\/#organization","name":"Conspiration | \u00c9ditions","url":"https:\/\/conspiration-editions.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/conspiration-editions.com\/#\/schema\/logo\/image\/","url":"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2021\/01\/cropped-cropped-cropped-logo-editions.png","contentUrl":"https:\/\/conspiration-editions.com\/wp-content\/uploads\/2021\/01\/cropped-cropped-cropped-logo-editions.png","width":574,"height":100,"caption":"Conspiration | \u00c9ditions"},"image":{"@id":"https:\/\/conspiration-editions.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/pages\/5946"}],"collection":[{"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/comments?post=5946"}],"version-history":[{"count":50,"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/pages\/5946\/revisions"}],"predecessor-version":[{"id":12330,"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/pages\/5946\/revisions\/12330"}],"wp:attachment":[{"href":"https:\/\/conspiration-editions.com\/en\/wp-json\/wp\/v2\/media?parent=5946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}